{"id":1861,"date":"2018-05-23T16:05:10","date_gmt":"2018-05-23T21:05:10","guid":{"rendered":"http:\/\/www.visualbit.co\/sanluis\/?p=1861"},"modified":"2020-04-23T16:06:52","modified_gmt":"2020-04-23T21:06:52","slug":"personaje-de-la-semana","status":"publish","type":"post","link":"https:\/\/www.sanluisrey.edu.co\/new\/personaje-de-la-semana\/","title":{"rendered":"Personaje de la Semana"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"1861\" class=\"elementor elementor-1861\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9c81f15 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9c81f15\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ad72af4\" data-id=\"ad72af4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b18eb70 elementor-widget elementor-widget-heading\" data-id=\"b18eb70\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Personaje de la Semana<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-950efd1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"950efd1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6787008\" data-id=\"6787008\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ab30896 elementor-widget elementor-widget-image\" data-id=\"ab30896\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"750\" height=\"563\" src=\"https:\/\/www.sanluisrey.edu.co\/new\/wp-content\/uploads\/2020\/04\/PersonajeDeLaSemana-1024x768.jpg\" class=\"attachment-large size-large wp-image-1865\" alt=\"\" srcset=\"https:\/\/www.sanluisrey.edu.co\/new\/wp-content\/uploads\/2020\/04\/PersonajeDeLaSemana-1024x768.jpg 1024w, https:\/\/www.sanluisrey.edu.co\/new\/wp-content\/uploads\/2020\/04\/PersonajeDeLaSemana-600x450.jpg 600w, https:\/\/www.sanluisrey.edu.co\/new\/wp-content\/uploads\/2020\/04\/PersonajeDeLaSemana-300x225.jpg 300w, https:\/\/www.sanluisrey.edu.co\/new\/wp-content\/uploads\/2020\/04\/PersonajeDeLaSemana-768x576.jpg 768w, https:\/\/www.sanluisrey.edu.co\/new\/wp-content\/uploads\/2020\/04\/PersonajeDeLaSemana.jpg 1280w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7828651 elementor-widget elementor-widget-text-editor\" data-id=\"7828651\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #333333; font-family: natural; font-size: 17px;\">Cadena Radial Caracol.<\/span><br style=\"color: #333333; font-family: natural; font-size: 17px;\" \/><span style=\"color: #333333; font-family: natural; font-size: 17px;\">Nuestra estudiante SOFIA GARCIA ARCILA,\u00a0<\/span><a class=\"_58cn\" href=\"https:\/\/web.facebook.com\/hashtag\/orgullosamentesanluisista?source=feed_text\" data-ft=\"{&quot;tn&quot;:&quot;*N&quot;,&quot;type&quot;:104}\" style=\"background: #ffffff; color: #428bca; font-family: natural; font-size: 17px;\"><span class=\"_5afx\"><span class=\"_58cl _5afz\" aria-label=\"numeral\">#<\/span><span class=\"_58cm\">Orgullosamentesanluisista<\/span><\/span><\/a><span style=\"color: #333333; font-family: natural; font-size: 17px;\">del grado 11B, fue destacada el d\u00eda 22 de abril como el personaje de la semana en la Cadena Radial Caracol. Este programa se trasmite todos los domingos y tiene como finalidad resaltar a las personalidades que se destacan; por aqu\u00ed han transitado historiadores, gobernantes, docentes, empresarios, asociaciones y un sin n\u00famero de personas que se destacan en nuestr<\/span><span class=\"text_exposed_show\" style=\"color: #333333; font-family: natural; font-size: 17px;\">o Quind\u00edo.<br \/>En esta oportunidad le toco a SOFIA, quien adem\u00e1s de ser excelente deportista y consagrada estudiante, hace parte de los escritores de la revista \u201cPROSA\u201d que desde el d\u00eda 21 de abril y de manera mensual, los amantes de la literatura podr\u00e1n degustar los escritos de los j\u00f3venes de la Escuela de Formaci\u00f3n Literaria Pensamiento Escrito, creadores de Prosa revista literaria, un impreso independiente en el que el lector podr\u00e1 encontrar poemas, ensayos cuentos y una amplia gama de g\u00e9neros en los que los autores plasman sus creencias, costumbres, criticas, an\u00e1lisis de la sociedad, historias, etc.<br \/>Felicitaciones a SOFIA.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Personaje de la Semana Cadena Radial Caracol.Nuestra estudiante SOFIA GARCIA ARCILA,\u00a0#Orgullosamentesanluisistadel grado 11B, fue destacada el d\u00eda 22 de abril como el personaje de la semana en la Cadena Radial Caracol. Este programa se trasmite todos los domingos y tiene como finalidad resaltar a las personalidades que se destacan; por [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"two_page_speed":[],"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[7],"tags":[],"class_list":["post-1861","post","type-post","status-publish","format-standard","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Personaje de la Semana - Colegio San Luis Rey<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sanluisrey.edu.co\/new\/personaje-de-la-semana\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Personaje de la Semana - Colegio San Luis Rey\" \/>\n<meta property=\"og:description\" content=\"Personaje de la Semana Cadena Radial Caracol.Nuestra estudiante SOFIA GARCIA ARCILA,\u00a0#Orgullosamentesanluisistadel grado 11B, fue destacada el d\u00eda 22 de abril como el personaje de la semana en la Cadena Radial Caracol. Este programa se trasmite todos los domingos y tiene como finalidad resaltar a las personalidades que se destacan; por [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sanluisrey.edu.co\/new\/personaje-de-la-semana\/\" \/>\n<meta property=\"og:site_name\" content=\"Colegio San Luis Rey\" \/>\n<meta property=\"article:author\" content=\"https:\/\/web.facebook.com\/sanluisreyarmenia\/?_rdc=1&amp;_rdr\" \/>\n<meta property=\"article:published_time\" content=\"2018-05-23T21:05:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-23T21:06:52+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.visualbit.co\/sanluis\/wp-content\/uploads\/2020\/04\/PersonajeDeLaSemana-1024x768.jpg\" \/>\n<meta name=\"author\" content=\"Colegio Franciscano San Luis Rey\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/san_luis_rey\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Colegio Franciscano San Luis Rey\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sanluisrey.edu.co\\\/new\\\/personaje-de-la-semana\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sanluisrey.edu.co\\\/new\\\/personaje-de-la-semana\\\/\"},\"author\":{\"name\":\"Colegio Franciscano San Luis Rey\",\"@id\":\"https:\\\/\\\/www.sanluisrey.edu.co\\\/new\\\/#\\\/schema\\\/person\\\/95c521ab3dc11c1a9bacf54769a78394\"},\"headline\":\"Personaje de la Semana\",\"datePublished\":\"2018-05-23T21:05:10+00:00\",\"dateModified\":\"2020-04-23T21:06:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sanluisrey.edu.co\\\/new\\\/personaje-de-la-semana\\\/\"},\"wordCount\":183,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.sanluisrey.edu.co\\\/new\\\/personaje-de-la-semana\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.visualbit.co\\\/sanluis\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/PersonajeDeLaSemana-1024x768.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.sanluisrey.edu.co\\\/new\\\/personaje-de-la-semana\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sanluisrey.edu.co\\\/new\\\/personaje-de-la-semana\\\/\",\"url\":\"https:\\\/\\\/www.sanluisrey.edu.co\\\/new\\\/personaje-de-la-semana\\\/\",\"name\":\"Personaje de la Semana - Colegio San Luis Rey\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sanluisrey.edu.co\\\/new\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.sanluisrey.edu.co\\\/new\\\/personaje-de-la-semana\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sanluisrey.edu.co\\\/new\\\/personaje-de-la-semana\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.visualbit.co\\\/sanluis\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/PersonajeDeLaSemana-1024x768.jpg\",\"datePublished\":\"2018-05-23T21:05:10+00:00\",\"dateModified\":\"2020-04-23T21:06:52+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.sanluisrey.edu.co\\\/new\\\/#\\\/schema\\\/person\\\/95c521ab3dc11c1a9bacf54769a78394\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sanluisrey.edu.co\\\/new\\\/personaje-de-la-semana\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sanluisrey.edu.co\\\/new\\\/personaje-de-la-semana\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.sanluisrey.edu.co\\\/new\\\/personaje-de-la-semana\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.visualbit.co\\\/sanluis\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/PersonajeDeLaSemana-1024x768.jpg\",\"contentUrl\":\"http:\\\/\\\/www.visualbit.co\\\/sanluis\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/PersonajeDeLaSemana-1024x768.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sanluisrey.edu.co\\\/new\\\/personaje-de-la-semana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.sanluisrey.edu.co\\\/new\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Personaje de la Semana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sanluisrey.edu.co\\\/new\\\/#website\",\"url\":\"https:\\\/\\\/www.sanluisrey.edu.co\\\/new\\\/\",\"name\":\"Colegio San Luis Rey\",\"description\":\"Comunidad Franciscana Provincia de la Santa Fe\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sanluisrey.edu.co\\\/new\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sanluisrey.edu.co\\\/new\\\/#\\\/schema\\\/person\\\/95c521ab3dc11c1a9bacf54769a78394\",\"name\":\"Colegio Franciscano San Luis Rey\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe07d4fe7d07e705f3dcebbfb00bd721c65e9deca5b80342bbf641330ea86b26?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe07d4fe7d07e705f3dcebbfb00bd721c65e9deca5b80342bbf641330ea86b26?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe07d4fe7d07e705f3dcebbfb00bd721c65e9deca5b80342bbf641330ea86b26?s=96&d=mm&r=g\",\"caption\":\"Colegio Franciscano San Luis Rey\"},\"sameAs\":[\"https:\\\/\\\/www.sanluisrey.edu.co\",\"https:\\\/\\\/web.facebook.com\\\/sanluisreyarmenia\\\/?_rdc=1&_rdr\",\"https:\\\/\\\/www.instagram.com\\\/colegiofranciscanosanluisrey\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/san_luis_rey\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/colegiosanluisrey\\\/\"],\"url\":\"https:\\\/\\\/www.sanluisrey.edu.co\\\/new\\\/author\\\/adminrey\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Personaje de la Semana - Colegio San Luis Rey","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sanluisrey.edu.co\/new\/personaje-de-la-semana\/","og_locale":"es_ES","og_type":"article","og_title":"Personaje de la Semana - Colegio San Luis Rey","og_description":"Personaje de la Semana Cadena Radial Caracol.Nuestra estudiante SOFIA GARCIA ARCILA,\u00a0#Orgullosamentesanluisistadel grado 11B, fue destacada el d\u00eda 22 de abril como el personaje de la semana en la Cadena Radial Caracol. Este programa se trasmite todos los domingos y tiene como finalidad resaltar a las personalidades que se destacan; por [&hellip;]","og_url":"https:\/\/www.sanluisrey.edu.co\/new\/personaje-de-la-semana\/","og_site_name":"Colegio San Luis Rey","article_author":"https:\/\/web.facebook.com\/sanluisreyarmenia\/?_rdc=1&_rdr","article_published_time":"2018-05-23T21:05:10+00:00","article_modified_time":"2020-04-23T21:06:52+00:00","og_image":[{"url":"http:\/\/www.visualbit.co\/sanluis\/wp-content\/uploads\/2020\/04\/PersonajeDeLaSemana-1024x768.jpg","type":"","width":"","height":""}],"author":"Colegio Franciscano San Luis Rey","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/san_luis_rey","twitter_misc":{"Escrito por":"Colegio Franciscano San Luis Rey","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sanluisrey.edu.co\/new\/personaje-de-la-semana\/#article","isPartOf":{"@id":"https:\/\/www.sanluisrey.edu.co\/new\/personaje-de-la-semana\/"},"author":{"name":"Colegio Franciscano San Luis Rey","@id":"https:\/\/www.sanluisrey.edu.co\/new\/#\/schema\/person\/95c521ab3dc11c1a9bacf54769a78394"},"headline":"Personaje de la Semana","datePublished":"2018-05-23T21:05:10+00:00","dateModified":"2020-04-23T21:06:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sanluisrey.edu.co\/new\/personaje-de-la-semana\/"},"wordCount":183,"commentCount":0,"image":{"@id":"https:\/\/www.sanluisrey.edu.co\/new\/personaje-de-la-semana\/#primaryimage"},"thumbnailUrl":"http:\/\/www.visualbit.co\/sanluis\/wp-content\/uploads\/2020\/04\/PersonajeDeLaSemana-1024x768.jpg","articleSection":["Noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.sanluisrey.edu.co\/new\/personaje-de-la-semana\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.sanluisrey.edu.co\/new\/personaje-de-la-semana\/","url":"https:\/\/www.sanluisrey.edu.co\/new\/personaje-de-la-semana\/","name":"Personaje de la Semana - Colegio San Luis Rey","isPartOf":{"@id":"https:\/\/www.sanluisrey.edu.co\/new\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sanluisrey.edu.co\/new\/personaje-de-la-semana\/#primaryimage"},"image":{"@id":"https:\/\/www.sanluisrey.edu.co\/new\/personaje-de-la-semana\/#primaryimage"},"thumbnailUrl":"http:\/\/www.visualbit.co\/sanluis\/wp-content\/uploads\/2020\/04\/PersonajeDeLaSemana-1024x768.jpg","datePublished":"2018-05-23T21:05:10+00:00","dateModified":"2020-04-23T21:06:52+00:00","author":{"@id":"https:\/\/www.sanluisrey.edu.co\/new\/#\/schema\/person\/95c521ab3dc11c1a9bacf54769a78394"},"breadcrumb":{"@id":"https:\/\/www.sanluisrey.edu.co\/new\/personaje-de-la-semana\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sanluisrey.edu.co\/new\/personaje-de-la-semana\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.sanluisrey.edu.co\/new\/personaje-de-la-semana\/#primaryimage","url":"http:\/\/www.visualbit.co\/sanluis\/wp-content\/uploads\/2020\/04\/PersonajeDeLaSemana-1024x768.jpg","contentUrl":"http:\/\/www.visualbit.co\/sanluis\/wp-content\/uploads\/2020\/04\/PersonajeDeLaSemana-1024x768.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.sanluisrey.edu.co\/new\/personaje-de-la-semana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.sanluisrey.edu.co\/new\/"},{"@type":"ListItem","position":2,"name":"Personaje de la Semana"}]},{"@type":"WebSite","@id":"https:\/\/www.sanluisrey.edu.co\/new\/#website","url":"https:\/\/www.sanluisrey.edu.co\/new\/","name":"Colegio San Luis Rey","description":"Comunidad Franciscana Provincia de la Santa Fe","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sanluisrey.edu.co\/new\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.sanluisrey.edu.co\/new\/#\/schema\/person\/95c521ab3dc11c1a9bacf54769a78394","name":"Colegio Franciscano San Luis Rey","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/fe07d4fe7d07e705f3dcebbfb00bd721c65e9deca5b80342bbf641330ea86b26?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fe07d4fe7d07e705f3dcebbfb00bd721c65e9deca5b80342bbf641330ea86b26?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fe07d4fe7d07e705f3dcebbfb00bd721c65e9deca5b80342bbf641330ea86b26?s=96&d=mm&r=g","caption":"Colegio Franciscano San Luis Rey"},"sameAs":["https:\/\/www.sanluisrey.edu.co","https:\/\/web.facebook.com\/sanluisreyarmenia\/?_rdc=1&_rdr","https:\/\/www.instagram.com\/colegiofranciscanosanluisrey\/","https:\/\/x.com\/https:\/\/twitter.com\/san_luis_rey","https:\/\/www.youtube.com\/user\/colegiosanluisrey\/"],"url":"https:\/\/www.sanluisrey.edu.co\/new\/author\/adminrey\/"}]}},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.sanluisrey.edu.co\/new\/wp-json\/wp\/v2\/posts\/1861","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sanluisrey.edu.co\/new\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sanluisrey.edu.co\/new\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sanluisrey.edu.co\/new\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sanluisrey.edu.co\/new\/wp-json\/wp\/v2\/comments?post=1861"}],"version-history":[{"count":4,"href":"https:\/\/www.sanluisrey.edu.co\/new\/wp-json\/wp\/v2\/posts\/1861\/revisions"}],"predecessor-version":[{"id":1868,"href":"https:\/\/www.sanluisrey.edu.co\/new\/wp-json\/wp\/v2\/posts\/1861\/revisions\/1868"}],"wp:attachment":[{"href":"https:\/\/www.sanluisrey.edu.co\/new\/wp-json\/wp\/v2\/media?parent=1861"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sanluisrey.edu.co\/new\/wp-json\/wp\/v2\/categories?post=1861"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sanluisrey.edu.co\/new\/wp-json\/wp\/v2\/tags?post=1861"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}